{"id":1821,"date":"2021-08-20T11:19:46","date_gmt":"2021-08-20T13:19:46","guid":{"rendered":"https:\/\/sites.usp.br\/lbbp\/?p=1821"},"modified":"2023-08-06T11:37:49","modified_gmt":"2023-08-06T13:37:49","slug":"rp2","status":"publish","type":"post","link":"https:\/\/sites.usp.br\/lbbp\/rp2\/","title":{"rendered":"ACH0042 Resolu\u00e7\u00e3o de Problemas 2"},"content":{"rendered":"<div id=\"pl-1821\"  class=\"panel-layout\" ><div id=\"pg-1821-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1821-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1821-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p style=\"text-align: center;\"><strong>Biotecnologia<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Disciplina: ACH0042 - Resolu\u00e7\u00e3o de Problemas II<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Resoluci\u00f3n de Problemas II<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Problem Based Learning II<\/strong><\/p>\n<p><strong>Docentes Respons\u00e1veis<\/strong>:<\/p>\n<p>Prof. Dr. Diego Falceta Gon\u00e7alves<\/p>\n<p>Prof. Dr. Felipe Chambergo Alcalde<\/p>\n<p>Prof. Dr. Rodrigo Willemart<\/p>\n<p>Profa. Dra. T\u00e2nia Viel<\/p>\n<p>Profa. Dra. Viviane Abreu Nunes Cerqueira Dantas<\/p>\n<p><strong>Cr\u00e9ditos Aula:<\/strong> \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 4<\/p>\n<p><strong>Local:<\/strong> Ciclo B\u00e1sico - Bloco 1 - T\u00e9rreo - Sala 09 e Bloco 2 - T\u00e9rreo - Sala 09 - RP 1 a RP 11<\/p>\n<p><strong>Data:<\/strong> Segunda-feira, 14:00 \u2013 18:00 h<\/p>\n<p><strong>Objetivos<\/strong><\/p>\n<ul>\n<li>Identificar e desenvolver atividades interdisciplinares de pesquisa.<\/li>\n<li>Discutir, investigar e analisar problemas e apontar solu\u00e7\u00f5es na \u00e1rea de Biotecnologia, relevantes \u00e0 sociedade desde o ponto de vista social, \u00e9tico, legal, acad\u00eamico, cultural e cient\u00edfico.<\/li>\n<\/ul>\n<p><strong>Programa <\/strong><\/p>\n<p>A disciplina se prop\u00f5e a discutir, investigar e analisar o estado da arte da Biotecnologia e sua rela\u00e7\u00e3o aos problemas sociais, culturais, cient\u00edficos e suas express\u00f5es s\u00f3cio espaciais relacionados ao desenvolvimento da sociedade e \u00e0 realidade brasileira.<\/p>\n<p><strong>\u00a0<\/strong><strong>Avalia\u00e7\u00e3o<\/strong><\/p>\n<p>Ser\u00e3o realizadas, ao longo do semestre, por meio de apresenta\u00e7\u00e3o do projeto e do trabalho final. Cada avalia\u00e7\u00e3o ter\u00e1 uma nota e peso a ser definido, conforme o tutor respons\u00e1vel.<\/p>\n<p><strong>\u00a0<\/strong><strong>M\u00e9todo<\/strong><\/p>\n<p>Atividades expositivo-dialogadas, grupos de discuss\u00e3o e semin\u00e1rios.<\/p>\n<p><strong>\u00a0<\/strong><strong>Crit\u00e9rios de aprova\u00e7\u00e3o<\/strong><\/p>\n<p>Ao final do semestre cada aluno ter\u00e1 obtido uma M\u00e9dia Final, composta, pelas notas das apresenta\u00e7\u00f5es.<\/p>\n<p>M\u00e9dia Final igual ou superior a 5,0, aluno aprovado;<\/p>\n<p>M\u00e9dia Final entre 3,0 e 4,9 leva o aluno \u00e0 Prova de Recupera\u00e7\u00e3o;<\/p>\n<p>M\u00e9dia Final abaixo de 3,0, reprova\u00e7\u00e3o.<\/p>\n<p><strong>Norma de Recupera\u00e7\u00e3o<\/strong><\/p>\n<p>Os alunos que tiverem m\u00e9dia entre 3,0 e 4,9 e frequ\u00eancia acima de 75% ter\u00e3o o direito de fazer uma prova de recupera\u00e7\u00e3o. O aluno dever obter m\u00e9dia igual ou superior a 5,0 para ser aprovado<\/p>\n<p><strong>Bibliografia<\/strong><\/p>\n<p>- Artigos cient\u00edficos<\/p>\n<p>- Textos e livros relacionados ao tema de estudo<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-1821-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1821-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1821-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 style=\"text-align: center;\">Material da Disciplina<\/h2>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-1821-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1821-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1821-2-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><a href=\"https:\/\/sites.usp.br\/lbbp\/wp-content\/uploads\/sites\/464\/2023\/08\/Cronograma-RP-II-Biotec-2023.pdf\" target=\"_blank\" rel=\"noopener\">Cronograma de Atividades 2023-2<\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Biotecnologia Disciplina: ACH0042 &#8211; Resolu\u00e7\u00e3o de Problemas II Resoluci\u00f3n de Problemas II Problem Based Learning II Docentes Respons\u00e1veis: Prof. Dr. Diego Falceta Gon\u00e7alves Prof. Dr. Felipe Chambergo Alcalde Prof. Dr. Rodrigo Willemart Profa. Dra. T\u00e2nia Viel Profa. Dra. Viviane Abreu Nunes Cerqueira Dantas Cr\u00e9ditos Aula: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 4 Local: Ciclo B\u00e1sico &#8211; Bloco 1 &#8211; T\u00e9rreo<a href=\"https:\/\/sites.usp.br\/lbbp\/rp2\/\">[&#8230;]<\/a><\/p>\n","protected":false},"author":208,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-1821","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/sites.usp.br\/lbbp\/wp-json\/wp\/v2\/posts\/1821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.usp.br\/lbbp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.usp.br\/lbbp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.usp.br\/lbbp\/wp-json\/wp\/v2\/users\/208"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.usp.br\/lbbp\/wp-json\/wp\/v2\/comments?post=1821"}],"version-history":[{"count":3,"href":"https:\/\/sites.usp.br\/lbbp\/wp-json\/wp\/v2\/posts\/1821\/revisions"}],"predecessor-version":[{"id":2355,"href":"https:\/\/sites.usp.br\/lbbp\/wp-json\/wp\/v2\/posts\/1821\/revisions\/2355"}],"wp:attachment":[{"href":"https:\/\/sites.usp.br\/lbbp\/wp-json\/wp\/v2\/media?parent=1821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.usp.br\/lbbp\/wp-json\/wp\/v2\/categories?post=1821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.usp.br\/lbbp\/wp-json\/wp\/v2\/tags?post=1821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}