{"id":5834,"date":"2024-03-13T12:15:21","date_gmt":"2024-03-13T14:15:21","guid":{"rendered":"https:\/\/sites.usp.br\/psicousp\/?p=5834"},"modified":"2024-03-14T12:30:20","modified_gmt":"2024-03-14T14:30:20","slug":"5834-2","status":"publish","type":"post","link":"https:\/\/sites.usp.br\/psicousp\/5834-2\/","title":{"rendered":"Artigo discute a atratividade facial em diversos pa\u00edses do mundo"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00a0<a href=\"https:\/\/sites.usp.br\/psicousp\/wp-content\/uploads\/sites\/340\/2024\/03\/Captura-de-tela-2024-03-14-112352.png\"><img decoding=\"async\" class=\"size-full wp-image-5841 alignleft\" src=\"https:\/\/sites.usp.br\/psicousp\/wp-content\/uploads\/sites\/340\/2024\/03\/Captura-de-tela-2024-03-14-112352.png\" alt=\"\" width=\"136\" height=\"184\" \/><\/a>Alguma vez se perguntou o que faz com que algumas pessoas sejam consideradas mais atrativas que outras? Ou quais s\u00e3o os crit\u00e9rios de beleza nas diferentes culturas?<\/p>\n<p style=\"text-align: justify;\">Os professores Karel Kleisner, Petr Ture\u010dek, Adil Saribay, Ond\u0159ej Pavlovi\u010d, Juan David Leong\u00f3mez, Craig Roberts, Jan Havl\u00ed\u010dek, Jaroslava Varella Valentova, Silviu Apostol, Robert Mbe Akoko e Marco A.C. Varella pesquisaram sobre este t\u00f3pico no seu artigo\u00a0<em>Distinctiveness and femininity, rather than symmetry and masculinity, affect facial attractiveness across the world\u00a0<\/em>(2023).<\/p>\n<p style=\"text-align: justify;\">No artigo, os autores avaliam a atratividade facial em humanos tendo em conta diferentes componentes em v\u00e1rias popula\u00e7\u00f5es, ao mesmo tempo que combinaram a morfometria geom\u00e9trica de 72 marcos faciais frontais padronizados e uma estrutura estat\u00edstica bayesiana. Investigaram as prefer\u00eancias em ambos os sexos por tr\u00eas componentes estruturais da atratividade facial que s\u00e3o considerados indicadores de qualidade biol\u00f3gica: simetria, dimorfismo sexual e distintividade (isto \u00e9, o oposto da prototipicalidade, a apar\u00eancia m\u00e9dia da popula\u00e7\u00e3o).<\/p>\n<p style=\"text-align: justify;\">Com base numa grande amostra de fotografias padronizadas de rostos da v\u00e1rios indiv\u00edduos (n = 1.550) de 10 popula\u00e7\u00f5es ao redor do mundo (Brasil, Camar\u00f5es, Ch\u00e9quia, Col\u00f4mbia, \u00cdndia, Nam\u00edbia, Rom\u00e9nia, Turquia, Reino Unido e Vietname), foi descoberto que as faces mais protot\u00edpicas em cada popula\u00e7\u00e3o s\u00e3o avaliadas como mais atraentes. Al\u00e9m disso, corroboraram alguns resultados anteriores indicando um efeito positivo da feminilidade morfol\u00f3gica facial na avalia\u00e7\u00e3o por homens da atratividade facial feminina.<\/p>\n<p style=\"text-align: justify;\">Por\u00e9m, n\u00e3o acharam um fraco efeito da masculinidade morfol\u00f3gica na avalia\u00e7\u00e3o por mulheres da atratividade facial masculina. Por outra parte, na contram\u00e3o de v\u00e1rios estudos anteriores que sugerem que a simetria facial \u00e9 uma dos principais constituintes biol\u00f3gicos da atratividade facial humana, neste estudo a simetria facial n\u00e3o teve efeito nenhum na avalia\u00e7\u00e3o de atratividade facial. Em conjunto com outros estudos recentes, os resultados apoiam a import\u00e2ncia da prototipicidade facial (apar\u00eancia m\u00e9dia da dada popula\u00e7\u00e3o) na percep\u00e7\u00e3o da atratividade f\u00edsica. Assim, apesar da simetria e a prototipicalidade estarem correlacionadas, \u00e9 a prototipicalidade que \u00e9 levada em considera\u00e7\u00e3o quando avaliamos atratividade facial alheia.<\/p>\n<p style=\"text-align: justify;\">Os autores conclu\u00edram que a avalia\u00e7\u00e3o de atratividade facial humana varia pouco entre popula\u00e7\u00f5es e pode ser prevista de forma robusta apenas considerando a distintividade e a feminilidade. Os autores convidam a fazer futuras pesquisas que tenham amostrar tamb\u00e9m a Oce\u00e2nia ou um conjunto mais diversificado de pa\u00edses em cada continente.<\/p>\n<p style=\"text-align: justify;\">As condi\u00e7\u00f5es de obten\u00e7\u00e3o das fotos para est\u00edmulos faciais e coleta das avalia\u00e7\u00f5es de atratividade n\u00e3o foram totalmente padronizadas entre cada pa\u00eds devido a restri\u00e7\u00f5es de infraestrutura local; isso tamb\u00e9m daria para fazer uma futura pesquisa com uma maior padroniza\u00e7\u00e3o. Estudos futuros devem tentar superar essas limita\u00e7\u00f5es e expandir esta abordagem transcultural e multicomponente da atratividade facial. No entanto, os autores tem oferecido uma abordagem mais global e ecologicamente v\u00e1lida para definir a import\u00e2ncia relativa de padr\u00f5es com base biol\u00f3gica de atratividade facial em humanos.<\/p>\n<p style=\"text-align: justify;\">O estudo foi liderado pelos pesquisadores tchecos e brasileiros, e desenvolvido em colabora\u00e7\u00e3o com outros pesquisadores brasileiros, tchecos, ingleses, turcos, colombianos, romenos e camaronenses, e publicado em revista internacional A1 (Evolution and Human Behavior). Al\u00e9m de outras ag\u00eancias de fomento, o estudo foi apoiado pela CAPES e CNPq.<\/p>\n<p>Se tiver interesse em ler o artigo completo,\u00a0<a href=\"https:\/\/www.sciencedirect.com\/science\/article\/pii\/S1090513823000879?dgcid=author\">acesse pelo seguinte link.<\/a><\/p>\n<p>Imagens: Igor Souza<br \/>\nRedatores: Jaroslava Varella e Daniela Rocha<br \/>\nPostagem: Mariana Pizzol<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Alguma vez se perguntou o que faz com que algumas pessoas sejam consideradas mais atrativas que outras? Ou quais s\u00e3o&#46;&#46;&#46;<\/p>\n","protected":false},"author":610,"featured_media":5836,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-5834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedade"],"_links":{"self":[{"href":"https:\/\/sites.usp.br\/psicousp\/wp-json\/wp\/v2\/posts\/5834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.usp.br\/psicousp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.usp.br\/psicousp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.usp.br\/psicousp\/wp-json\/wp\/v2\/users\/610"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.usp.br\/psicousp\/wp-json\/wp\/v2\/comments?post=5834"}],"version-history":[{"count":4,"href":"https:\/\/sites.usp.br\/psicousp\/wp-json\/wp\/v2\/posts\/5834\/revisions"}],"predecessor-version":[{"id":5845,"href":"https:\/\/sites.usp.br\/psicousp\/wp-json\/wp\/v2\/posts\/5834\/revisions\/5845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.usp.br\/psicousp\/wp-json\/wp\/v2\/media\/5836"}],"wp:attachment":[{"href":"https:\/\/sites.usp.br\/psicousp\/wp-json\/wp\/v2\/media?parent=5834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.usp.br\/psicousp\/wp-json\/wp\/v2\/categories?post=5834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.usp.br\/psicousp\/wp-json\/wp\/v2\/tags?post=5834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}