{"id":31,"date":"2021-11-10T15:01:18","date_gmt":"2021-11-10T18:01:18","guid":{"rendered":"https:\/\/sites.usp.br\/redlibre\/?page_id=31"},"modified":"2021-11-25T10:57:05","modified_gmt":"2021-11-25T13:57:05","slug":"contato","status":"publish","type":"page","link":"https:\/\/sites.usp.br\/redlibre\/sobre\/contato\/","title":{"rendered":"Contato"},"content":{"rendered":"<p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f296-o1\" lang=\"pt-BR\" dir=\"ltr\" data-wpcf7-id=\"296\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/redlibre\/wp-json\/wp\/v2\/pages\/31#wpcf7-f296-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rios de contato\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"296\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pt_BR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f296-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> Nome<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> E-mail<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Assunto<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Mensagem<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/p>\n<hr \/>\n<p><strong>Redlibre<\/strong><\/p>\n<p>Faculdade de Medicina, Universidade de S\u00e3o Paulo<\/p>\n<p>Avenida Doutor Arnaldo, 455 &#8211; Sala 2177 &#8211; Cerqueira C\u00e9sar<\/p>\n<p>Tel. 05511.30617089 &#8211; CEP. 01246-903 &#8211; S\u00e3o Paulo &#8211; SP &#8211; Brasil<\/p>\n<hr \/>\n<p>Facultad de Ciencias Pol\u00edticas y Sociolog\u00eda<\/p>\n<p>Departamento de Antropolog\u00eda Social y Psicolog\u00eda Social<\/p>\n<p>Universidad Complutense de Madrid<\/p>\n<p>Campus de Somosaguas &#8211; 28223 &#8211; Pozuelo de Alarc\u00f3n<\/p>\n<p>Madrid &#8211; Espa\u00f1a<\/p>\n<p>email: <a href=\"mailto:rmachin@usp.br\">redelibre@gmail.com<\/a><\/p>\n<hr \/>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Redlibre Faculdade de Medicina, Universidade de S\u00e3o Paulo Avenida Doutor Arnaldo, 455 &#8211; Sala 2177 &#8211; Cerqueira C\u00e9sar Tel. 05511.30617089 &#8211; CEP. 01246-903 &#8211; S\u00e3o Paulo &#8211; SP &#8211; Brasil Facultad de Ciencias Pol\u00edticas y Sociolog\u00eda Departamento de Antropolog\u00eda Social y Psicolog\u00eda Social Universidad Complutense de Madrid Campus de Somosaguas &#8211; 28223 &#8211; Pozuelo de [&hellip;]<\/p>\n","protected":false},"author":22325,"featured_media":0,"parent":15,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-31","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/sites.usp.br\/redlibre\/wp-json\/wp\/v2\/pages\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.usp.br\/redlibre\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sites.usp.br\/redlibre\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sites.usp.br\/redlibre\/wp-json\/wp\/v2\/users\/22325"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.usp.br\/redlibre\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":5,"href":"https:\/\/sites.usp.br\/redlibre\/wp-json\/wp\/v2\/pages\/31\/revisions"}],"predecessor-version":[{"id":299,"href":"https:\/\/sites.usp.br\/redlibre\/wp-json\/wp\/v2\/pages\/31\/revisions\/299"}],"up":[{"embeddable":true,"href":"https:\/\/sites.usp.br\/redlibre\/wp-json\/wp\/v2\/pages\/15"}],"wp:attachment":[{"href":"https:\/\/sites.usp.br\/redlibre\/wp-json\/wp\/v2\/media?parent=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}